{"id":35897,"date":"2025-05-22T07:45:07","date_gmt":"2025-05-22T10:45:07","guid":{"rendered":"https:\/\/www.grupomedcof.com.br\/blog\/?p=35897"},"modified":"2025-05-22T07:45:09","modified_gmt":"2025-05-22T10:45:09","slug":"entenda-tudo-sobre-o-linfogranuloma-venereo","status":"publish","type":"post","link":"https:\/\/www.grupomedcof.com.br\/blog\/entenda-tudo-sobre-o-linfogranuloma-venereo\/","title":{"rendered":"Entenda tudo sobre o Linfogranuloma Ven\u00e9reo"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/05\/Blog-MedCof-2025-05-21T131751.468-1024x576.jpg\" alt=\"\" class=\"wp-image-35898\" srcset=\"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/05\/Blog-MedCof-2025-05-21T131751.468-1024x576.jpg 1024w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/05\/Blog-MedCof-2025-05-21T131751.468-300x169.jpg 300w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/05\/Blog-MedCof-2025-05-21T131751.468-768x432.jpg 768w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/05\/Blog-MedCof-2025-05-21T131751.468-1536x864.jpg 1536w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/05\/Blog-MedCof-2025-05-21T131751.468-747x420.jpg 747w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/05\/Blog-MedCof-2025-05-21T131751.468-150x84.jpg 150w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/05\/Blog-MedCof-2025-05-21T131751.468-696x392.jpg 696w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/05\/Blog-MedCof-2025-05-21T131751.468-1068x601.jpg 1068w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/05\/Blog-MedCof-2025-05-21T131751.468.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Imagem: Canva.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">O <strong>linfogranuloma ven\u00e9reo (LGV)<\/strong>, tamb\u00e9m conhecido como doen\u00e7a de <strong>Nicolas-Favre-Durand,<\/strong> acomete pacientes que tiveram <strong>rela\u00e7\u00f5es sexuais desprotegidas<\/strong> e que foram infectados pela <strong><em>C.trachomatis.<\/em><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-o-que-e-a-doenca-de-nicolas-favre-durand\"><strong>O que \u00e9 a doen\u00e7a de Nicolas-Favre-Durand?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O nome da doen\u00e7a se justifica pelo empenho desses 3 cientistas em investigar a condi\u00e7\u00e3o no ano de 1913, apoiados pelo Instituto de Medicina Experimental de Buenos Aires. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eles caracterizam o LGV como uma IST de <strong>transmiss\u00e3o exclusiva por via sexual e etiologia bacteriana.<\/strong> \u00c9 uma doen\u00e7a causada pelos sorotipos <strong>L1, L2 e L3 da <em>Chlamydia trachomatis,<\/em><\/strong> que acomete os tecidos linf\u00e1ticos.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXca1GkJVkL8Zgw41hDn-LtdKCGF2X8kBZUKfwBDoyhvWPTpzBgpFlzYAJVMPfRQMG--Rxj-h3VcaeC7Nak6efz8Vu306dyXPUgWuyl7pBQoPchaF1jhBQY3JDsNcTuVCd_0QahsMQ?key=qJpdOYQ3pX3zW89FfW25xg\" alt=\"\"\/><figcaption class=\"wp-element-caption\">Bact\u00e9ria <em>Chlamydia trachomatis<\/em> na zona de transi\u00e7\u00e3o do colo uterino. Fonte: <a href=\"https:\/\/screening.iarc.fr\/atlasglossdef.php?lang=4&amp;key=Clamidia&amp;img=cyto6608\">https:\/\/screening.iarc.fr\/atlasglossdef.php?lang=4&amp;key=Clamidia&amp;img=cyto6608<\/a>\u00a0<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-estagios-do-linfogranuloma-venereo\"><strong>Est\u00e1gios do Linfogranuloma Ven\u00e9reo<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-estagio-primario\"><strong>Est\u00e1gio Prim\u00e1rio<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O per\u00edodo de incuba\u00e7\u00e3o varia de 3 a 30 dias. O in\u00edcio do quadro cl\u00ednico \u00e9 caracterizado pela <strong>les\u00e3o de inocula\u00e7\u00e3o<\/strong>, que costuma ser indolor, transit\u00f3ria e impercept\u00edvel. Essa les\u00e3o geralmente se apresenta em forma de <strong>p\u00e1pula<\/strong>, ulcera\u00e7\u00e3o superficial, eros\u00e3o ou como uma les\u00e3o herpetiforme.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXesyf25VQ8gvc8S71ZTDKL8NkFG9k53kEAuO8gbx69SaQbOMqskl9TJB6UMzgPGsLQnHQ6ilkHlwueTxZFu2KoXyusGioThqDopz873kiXM1UcPTbEXUtV4Xx7awplVrAG-PEld?key=qJpdOYQ3pX3zW89FfW25xg\" alt=\"\"\/><figcaption class=\"wp-element-caption\">Les\u00e3o transit\u00f3ria e indolor. Fonte: Google Imagens.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Nos homens, costuma aparecer em regi\u00e3o de glande, fr\u00eanulo, prep\u00facio e escroto. Nas mulheres, acomete a parede posterior da vagina e a c\u00e9rvice.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-estagio-secundario-sindrome-inguinal\"><strong>Est\u00e1gio Secund\u00e1rio &#8211; S\u00edndrome Inguinal<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O 2\u00ba est\u00e1gio da doen\u00e7a ocorre ap\u00f3s<strong> 2 a 6 semanas do surgimento da les\u00e3o de inocula\u00e7\u00e3o<\/strong> e \u00e9 caracterizado pela <strong>dissemina\u00e7\u00e3o linf\u00e1tica e acometimento ganglionar,<\/strong> geralmente unilateral. Nos homens, tem-se <strong>linfadenite inguinal<\/strong>. J\u00e1 nas mulheres, por conta da drenagem ser diferente, temos linfadenite retroperitoneal.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXc_hYltwwg3Ka60oy6ZyE7cLlUdVJ36QW3bstf0MSx1PT3Z-V8Vjk9G9HupoIhJ1ypPi90jhunVAuUplX-BofsO7CSwE0QWuJ4XuIPeeYmR8SwLiftZkiZSbjMA3LEvEyz8IdeyTQ?key=qJpdOYQ3pX3zW89FfW25xg\" alt=\"\"\/><figcaption class=\"wp-element-caption\">Bub\u00e3o inguinal. Fonte: Google Imagens.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Os g\u00e2nglios acometidos tornam-se r\u00edgidos, dolorosos e m\u00f3veis. Por\u00e9m, rapidamente aderem \u00e0 pele, formando o \u201c<strong>bub\u00e3o inguinal<\/strong>\u201d, causando<strong> eritematoedema e descama\u00e7\u00e3o. <\/strong>Em at\u00e9 1\/3 dos casos, o bub\u00e3o inguinal se rompe, liberando drenagem de secre\u00e7\u00e3o purulenta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m podem ocorrer manifesta\u00e7\u00f5es sist\u00eamicas inespec\u00edficas, como: <strong>febre, mal-estar, anorexia, cefaleia, artralgias, emagrecimento, sudorese noturna e hepatoesplenomegalia. <\/strong>Em alguns casos, tamb\u00e9m est\u00e3o presentes manifesta\u00e7\u00f5es dermatol\u00f3gicas, como eritema nodoso, eritema polimorfo, urtic\u00e1ria e exantema maculopapular.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-estagio-terciario-sindrome-anogenital\"><strong>Est\u00e1gio Terci\u00e1rio &#8211; S\u00edndrome Anogenital<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m conhecida como <strong>fase de sequelas<\/strong>, que resultam das les\u00f5es progressivas, hipertr\u00f3ficas e necr\u00f3ticas. Ocorre principalmente em mulheres, devido \u00e0 drenagem retroperitoneal, e \u00e9 caracterizada por:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Proctite leve com muco, sangue e pus nas fezes.<\/li>\n\n\n\n<li>Tenesmo.<\/li>\n\n\n\n<li>Febre.<\/li>\n\n\n\n<li>Emagrecimento.<\/li>\n\n\n\n<li>Dor.<\/li>\n\n\n\n<li>Fibrose e estenose retal.<\/li>\n\n\n\n<li>Abscessos peritoneais.<\/li>\n\n\n\n<li>Linfedema de genit\u00e1lia externa.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>fibrose e a estenose retal<\/strong> podem levar a obstru\u00e7\u00f5es intestinais e complica\u00e7\u00f5es graves, exigindo interven\u00e7\u00e3o cir\u00fargica em alguns casos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-diagnostico-do-linfogranuloma-venereo\"><strong>Diagn\u00f3stico do Linfogranuloma Ven\u00e9reo<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O diagn\u00f3stico \u00e9 <strong>cl\u00ednico<\/strong>, n\u00e3o sendo necess\u00e1rios exames complementares. Entretanto, podemos lan\u00e7ar m\u00e3o de alguns exames, como:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Exame direto do esfrega\u00e7o.<\/li>\n\n\n\n<li>Imunofluoresc\u00eancia direta.<\/li>\n\n\n\n<li>Sorologia para <em>Chlamydia trachomatis.<\/em><\/li>\n\n\n\n<li>Cultura.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-como-tratar-o-linfogranuloma-venereo\"><strong>Como tratar o Linfogranuloma Ven\u00e9reo?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O tratamento de escolha \u00e9 feito com <strong>Doxiciclina 100mg VO 12\/12h por 21 dias.<\/strong> Uma alternativa \u00e9 o uso de <strong>eritromicina 500mg VO 6\/6h por 21 dias.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"conquiste-a-aprova\u00e7\u00e3o\"><strong>O m\u00e9todo que te aprova!<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Quer alcan\u00e7ar a aprova\u00e7\u00e3o nas provas de resid\u00eancia m\u00e9dica? Ent\u00e3o seja um&nbsp;<a href=\"https:\/\/www.grupomedcof.com.br\/home\/\" target=\"_blank\" rel=\"noreferrer noopener\">MedCoffer<\/a>! Aqui te ajudaremos na busca da aprova\u00e7\u00e3o com conte\u00fados de qualidade e uma&nbsp;<a href=\"https:\/\/www.grupomedcof.com.br\/blog\/presenca-da-medcof-nas-aprovacoes-em-residencia-medica-no-brasil\/\" target=\"_blank\" rel=\"noreferrer noopener\">metodologia que j\u00e1 aprovou mais de 10 mil residentes no pa\u00eds!&nbsp;<\/a>Por fim, acesse o nosso<a href=\"https:\/\/www.youtube.com\/@GrupoMedcof\/featured\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;<strong>canal do youtube&nbsp;<\/strong><\/a>para ver o nosso material.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"youtube-embed\" data-video_id=\"ABWsVpQVvoU\"><iframe loading=\"lazy\" title=\"SingularCast T2 Ep.28 - Dra. Patr\u00edcia Magalh\u00e3es aprovada em Cardiologia no Dante, UNIFESP e UNICAMP\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/ABWsVpQVvoU?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>O linfogranuloma ven\u00e9reo (LGV) tamb\u00e9m \u00e9 conhecido como doen\u00e7a de Nicolas-Favre-Durand. Veja mais e entenda!<\/p>\n","protected":false},"author":18,"featured_media":35898,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[125],"tags":[290,2923,2924,68],"ppma_author":[3611],"class_list":["post-35897","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ginecologia-e-obstetricia","tag-ist","tag-lgv","tag-linfogranuloma-venereo","tag-residencia-medica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Entenda tudo sobre o Linfogranuloma Ven\u00e9reo - Blog de Medcof: conte\u00fados, editais, revalida e mais!<\/title>\n<meta name=\"description\" content=\"O linfogranuloma ven\u00e9reo (LGV) tamb\u00e9m \u00e9 conhecido como doen\u00e7a de Nicolas-Favre-Durand. Veja mais e entenda!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.grupomedcof.com.br\/blog\/entenda-tudo-sobre-o-linfogranuloma-venereo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entenda tudo sobre o Linfogranuloma Ven\u00e9reo\" \/>\n<meta property=\"og:description\" content=\"O linfogranuloma ven\u00e9reo (LGV) tamb\u00e9m \u00e9 conhecido como doen\u00e7a de Nicolas-Favre-Durand. Veja mais e entenda!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.grupomedcof.com.br\/blog\/entenda-tudo-sobre-o-linfogranuloma-venereo\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Medcof: conte\u00fados, editais, revalida e mais!\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MedCofQbank\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-22T10:45:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-22T10:45:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/05\/Blog-MedCof-2025-05-21T131751.468.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leila Menzel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leila Menzel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/entenda-tudo-sobre-o-linfogranuloma-venereo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/entenda-tudo-sobre-o-linfogranuloma-venereo\\\/\"},\"author\":{\"name\":\"Leila Menzel\",\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f5463ef12b38f0b64f5a738946f00f68\"},\"headline\":\"Entenda tudo sobre o Linfogranuloma Ven\u00e9reo\",\"datePublished\":\"2025-05-22T10:45:07+00:00\",\"dateModified\":\"2025-05-22T10:45:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/entenda-tudo-sobre-o-linfogranuloma-venereo\\\/\"},\"wordCount\":611,\"publisher\":{\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/entenda-tudo-sobre-o-linfogranuloma-venereo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Blog-MedCof-2025-05-21T131751.468.jpg\",\"keywords\":[\"IST\",\"LGV\",\"Linfogranuloma Ven\u00e9reo\",\"Resid\u00eancia M\u00e9dica\"],\"articleSection\":[\"Ginecologia e Obstetr\u00edcia\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/entenda-tudo-sobre-o-linfogranuloma-venereo\\\/\",\"url\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/entenda-tudo-sobre-o-linfogranuloma-venereo\\\/\",\"name\":\"Entenda tudo sobre o Linfogranuloma Ven\u00e9reo - Blog de Medcof: conte\u00fados, editais, revalida e mais!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/entenda-tudo-sobre-o-linfogranuloma-venereo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/entenda-tudo-sobre-o-linfogranuloma-venereo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Blog-MedCof-2025-05-21T131751.468.jpg\",\"datePublished\":\"2025-05-22T10:45:07+00:00\",\"dateModified\":\"2025-05-22T10:45:09+00:00\",\"description\":\"O linfogranuloma ven\u00e9reo (LGV) tamb\u00e9m \u00e9 conhecido como doen\u00e7a de Nicolas-Favre-Durand. Veja mais e entenda!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/entenda-tudo-sobre-o-linfogranuloma-venereo\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/entenda-tudo-sobre-o-linfogranuloma-venereo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/entenda-tudo-sobre-o-linfogranuloma-venereo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Blog-MedCof-2025-05-21T131751.468.jpg\",\"contentUrl\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Blog-MedCof-2025-05-21T131751.468.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Imagem: Canva.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/entenda-tudo-sobre-o-linfogranuloma-venereo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entenda tudo sobre o Linfogranuloma Ven\u00e9reo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/\",\"name\":\"Blog de Medcof: conte\u00fados, editais, revalida e mais!\",\"description\":\"Acesso o blog de MedCof! Seu portal de conte\u00fados sobre resid\u00eancia m\u00e9dica, an\u00e1lise e editais e muito mais. Clique e confira!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/#organization\"},\"alternateName\":\"Blog de Medcof: conte\u00fados, editais, revalida e mais!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/#organization\",\"name\":\"Grupo MedCof\",\"url\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-medcof.png\",\"contentUrl\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-medcof.png\",\"width\":768,\"height\":269,\"caption\":\"Grupo MedCof\"},\"image\":{\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MedCofQbank\\\/\",\"https:\\\/\\\/www.instagram.com\\\/grupomedcof\\\/\",\"https:\\\/\\\/br.linkedin.com\\\/company\\\/medcof\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCdHMuOHKICxcHwecxN8P-AA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f5463ef12b38f0b64f5a738946f00f68\",\"name\":\"Leila Menzel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-logo-96x96.png15459389df217b605b4f0cce419ac81a\",\"url\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-logo-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-cropped-cropped-logo-96x96.png\",\"caption\":\"Leila Menzel\"},\"description\":\"Estudante do 7\u00b0 semestre de jornalismo. Atuo na cobertura de not\u00edcias e atualiza\u00e7\u00f5es sobre sa\u00fade, com foco em resid\u00eancia m\u00e9dica.\",\"url\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/author\\\/leila\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Entenda tudo sobre o Linfogranuloma Ven\u00e9reo - Blog de Medcof: conte\u00fados, editais, revalida e mais!","description":"O linfogranuloma ven\u00e9reo (LGV) tamb\u00e9m \u00e9 conhecido como doen\u00e7a de Nicolas-Favre-Durand. Veja mais e entenda!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.grupomedcof.com.br\/blog\/entenda-tudo-sobre-o-linfogranuloma-venereo\/","og_locale":"pt_BR","og_type":"article","og_title":"Entenda tudo sobre o Linfogranuloma Ven\u00e9reo","og_description":"O linfogranuloma ven\u00e9reo (LGV) tamb\u00e9m \u00e9 conhecido como doen\u00e7a de Nicolas-Favre-Durand. Veja mais e entenda!","og_url":"https:\/\/www.grupomedcof.com.br\/blog\/entenda-tudo-sobre-o-linfogranuloma-venereo\/","og_site_name":"Blog de Medcof: conte\u00fados, editais, revalida e mais!","article_publisher":"https:\/\/www.facebook.com\/MedCofQbank\/","article_published_time":"2025-05-22T10:45:07+00:00","article_modified_time":"2025-05-22T10:45:09+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/05\/Blog-MedCof-2025-05-21T131751.468.jpg","type":"image\/jpeg"}],"author":"Leila Menzel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Leila Menzel","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.grupomedcof.com.br\/blog\/entenda-tudo-sobre-o-linfogranuloma-venereo\/#article","isPartOf":{"@id":"https:\/\/www.grupomedcof.com.br\/blog\/entenda-tudo-sobre-o-linfogranuloma-venereo\/"},"author":{"name":"Leila Menzel","@id":"https:\/\/www.grupomedcof.com.br\/blog\/#\/schema\/person\/f5463ef12b38f0b64f5a738946f00f68"},"headline":"Entenda tudo sobre o Linfogranuloma Ven\u00e9reo","datePublished":"2025-05-22T10:45:07+00:00","dateModified":"2025-05-22T10:45:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.grupomedcof.com.br\/blog\/entenda-tudo-sobre-o-linfogranuloma-venereo\/"},"wordCount":611,"publisher":{"@id":"https:\/\/www.grupomedcof.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.grupomedcof.com.br\/blog\/entenda-tudo-sobre-o-linfogranuloma-venereo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/05\/Blog-MedCof-2025-05-21T131751.468.jpg","keywords":["IST","LGV","Linfogranuloma Ven\u00e9reo","Resid\u00eancia M\u00e9dica"],"articleSection":["Ginecologia e Obstetr\u00edcia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.grupomedcof.com.br\/blog\/entenda-tudo-sobre-o-linfogranuloma-venereo\/","url":"https:\/\/www.grupomedcof.com.br\/blog\/entenda-tudo-sobre-o-linfogranuloma-venereo\/","name":"Entenda tudo sobre o Linfogranuloma Ven\u00e9reo - Blog de Medcof: conte\u00fados, editais, revalida e mais!","isPartOf":{"@id":"https:\/\/www.grupomedcof.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.grupomedcof.com.br\/blog\/entenda-tudo-sobre-o-linfogranuloma-venereo\/#primaryimage"},"image":{"@id":"https:\/\/www.grupomedcof.com.br\/blog\/entenda-tudo-sobre-o-linfogranuloma-venereo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/05\/Blog-MedCof-2025-05-21T131751.468.jpg","datePublished":"2025-05-22T10:45:07+00:00","dateModified":"2025-05-22T10:45:09+00:00","description":"O linfogranuloma ven\u00e9reo (LGV) tamb\u00e9m \u00e9 conhecido como doen\u00e7a de Nicolas-Favre-Durand. Veja mais e entenda!","breadcrumb":{"@id":"https:\/\/www.grupomedcof.com.br\/blog\/entenda-tudo-sobre-o-linfogranuloma-venereo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.grupomedcof.com.br\/blog\/entenda-tudo-sobre-o-linfogranuloma-venereo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.grupomedcof.com.br\/blog\/entenda-tudo-sobre-o-linfogranuloma-venereo\/#primaryimage","url":"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/05\/Blog-MedCof-2025-05-21T131751.468.jpg","contentUrl":"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/05\/Blog-MedCof-2025-05-21T131751.468.jpg","width":1920,"height":1080,"caption":"Imagem: Canva."},{"@type":"BreadcrumbList","@id":"https:\/\/www.grupomedcof.com.br\/blog\/entenda-tudo-sobre-o-linfogranuloma-venereo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.grupomedcof.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Entenda tudo sobre o Linfogranuloma Ven\u00e9reo"}]},{"@type":"WebSite","@id":"https:\/\/www.grupomedcof.com.br\/blog\/#website","url":"https:\/\/www.grupomedcof.com.br\/blog\/","name":"Blog de Medcof: conte\u00fados, editais, revalida e mais!","description":"Acesso o blog de MedCof! Seu portal de conte\u00fados sobre resid\u00eancia m\u00e9dica, an\u00e1lise e editais e muito mais. Clique e confira!","publisher":{"@id":"https:\/\/www.grupomedcof.com.br\/blog\/#organization"},"alternateName":"Blog de Medcof: conte\u00fados, editais, revalida e mais!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.grupomedcof.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.grupomedcof.com.br\/blog\/#organization","name":"Grupo MedCof","url":"https:\/\/www.grupomedcof.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.grupomedcof.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2022\/01\/logo-medcof.png","contentUrl":"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2022\/01\/logo-medcof.png","width":768,"height":269,"caption":"Grupo MedCof"},"image":{"@id":"https:\/\/www.grupomedcof.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MedCofQbank\/","https:\/\/www.instagram.com\/grupomedcof\/","https:\/\/br.linkedin.com\/company\/medcof","https:\/\/www.youtube.com\/channel\/UCdHMuOHKICxcHwecxN8P-AA"]},{"@type":"Person","@id":"https:\/\/www.grupomedcof.com.br\/blog\/#\/schema\/person\/f5463ef12b38f0b64f5a738946f00f68","name":"Leila Menzel","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-logo-96x96.png15459389df217b605b4f0cce419ac81a","url":"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-logo-96x96.png","contentUrl":"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-logo-96x96.png","caption":"Leila Menzel"},"description":"Estudante do 7\u00b0 semestre de jornalismo. Atuo na cobertura de not\u00edcias e atualiza\u00e7\u00f5es sobre sa\u00fade, com foco em resid\u00eancia m\u00e9dica.","url":"https:\/\/www.grupomedcof.com.br\/blog\/author\/leila\/"}]}},"authors":[{"term_id":3611,"user_id":18,"is_guest":0,"slug":"leila","display_name":"Leila Menzel","avatar_url":"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2023\/04\/cropped-cropped-cropped-logo-96x96.png","0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.grupomedcof.com.br\/blog\/wp-json\/wp\/v2\/posts\/35897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.grupomedcof.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.grupomedcof.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.grupomedcof.com.br\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.grupomedcof.com.br\/blog\/wp-json\/wp\/v2\/comments?post=35897"}],"version-history":[{"count":1,"href":"https:\/\/www.grupomedcof.com.br\/blog\/wp-json\/wp\/v2\/posts\/35897\/revisions"}],"predecessor-version":[{"id":35899,"href":"https:\/\/www.grupomedcof.com.br\/blog\/wp-json\/wp\/v2\/posts\/35897\/revisions\/35899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grupomedcof.com.br\/blog\/wp-json\/wp\/v2\/media\/35898"}],"wp:attachment":[{"href":"https:\/\/www.grupomedcof.com.br\/blog\/wp-json\/wp\/v2\/media?parent=35897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.grupomedcof.com.br\/blog\/wp-json\/wp\/v2\/categories?post=35897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.grupomedcof.com.br\/blog\/wp-json\/wp\/v2\/tags?post=35897"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.grupomedcof.com.br\/blog\/wp-json\/wp\/v2\/ppma_author?post=35897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}