{"id":44904,"date":"2026-05-28T11:16:58","date_gmt":"2026-05-28T14:16:58","guid":{"rendered":"https:\/\/www.grupomedcof.com.br\/blog\/?p=44904"},"modified":"2026-05-28T11:19:11","modified_gmt":"2026-05-28T14:19:11","slug":"unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados","status":"publish","type":"post","link":"https:\/\/www.grupomedcof.com.br\/blog\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\/","title":{"rendered":"UnirG pode ter mais de mil diplomas m\u00e9dicos revalidados anulados\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>Promotoria aponta uso de m\u00e9todo proibido, falta de editais e descumprimento de regras do Revalida pela UnirG; Justi\u00e7a deu 20 dias para a institui\u00e7\u00e3o se manifestar.\u00a0<br><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2026\/05\/Blog-MedCof-56-1024x576.jpg\" alt=\"UnirG pode ter mais de mil diplomas m\u00e9dicos revalidados anulados\u00a0\" class=\"wp-image-44910\" srcset=\"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2026\/05\/Blog-MedCof-56-1024x576.jpg 1024w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2026\/05\/Blog-MedCof-56-300x169.jpg 300w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2026\/05\/Blog-MedCof-56-768x432.jpg 768w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2026\/05\/Blog-MedCof-56-1536x864.jpg 1536w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2026\/05\/Blog-MedCof-56-747x420.jpg 747w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2026\/05\/Blog-MedCof-56-150x84.jpg 150w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2026\/05\/Blog-MedCof-56-696x392.jpg 696w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2026\/05\/Blog-MedCof-56-1068x601.jpg 1068w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2026\/05\/Blog-MedCof-56.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Nesta segunda-feira (25), o <strong>Minist\u00e9rio P\u00fablico do Tocantins (MPTO)<\/strong> entrou com uma a\u00e7\u00e3o civil p\u00fablica contra a<strong> Funda\u00e7\u00e3o UnirG e a Universidade de Gurupi (UnirG)<\/strong>. A a\u00e7\u00e3o visa a <strong>suspens\u00e3o imediata e futura anula\u00e7\u00e3o <\/strong>de todos os diplomas estrangeiros de Medicina revalidados pela institui\u00e7\u00e3o desde mar\u00e7o de 2025.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conforme avaliado pela a promotora de Justi\u00e7a Luma Gomides de Souza, titular da 3\u00aa Promotoria de Justi\u00e7a de Gurupi, a<strong> UnirG promoveu revalida\u00e7\u00f5es em um modelo pr\u00f3prio simplificado<\/strong>, o que est\u00e1 em desacordo com as normas federais e a resolu\u00e7\u00e3o de 2024 do Conselho Nacional de Educa\u00e7\u00e3o (CNE), que exige<strong> aprova\u00e7\u00e3o no Revalida.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conduzido pelo <strong>Instituto Nacional de Estudos e Pesquisas Educacionais An\u00edsio Teixeira (Inep)<\/strong>, o Revalida \u00e9 o \u00fanico meio para o m\u00e9dico formado no exterior revalidar o diploma no Brasil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em nota de esclarecimento divulgada em fevereiro de 2025, o Conselho Federal de Medicina (CFM) afirmou: \u201ca via simplificada \u00e9 uma exce\u00e7\u00e3o prevista em norma federal e s\u00f3 pode ser utilizada em situa\u00e7\u00f5es muito espec\u00edficas, [&#8230;]. Trata-se, portanto, de procedimento restrito e, para Medicina, sua ado\u00e7\u00e3o est\u00e1 expressamente vedada desde a entrada em vigor da Resolu\u00e7\u00e3o CNE\/CES n\u00ba 02\/2024, em janeiro do ano passado.\u201d<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.grupomedcof.com.br\/cofletters\/?clientId=&amp;utm_campaign=newsletter&amp;utm_medium=banner&amp;utm_source=blog&amp;utm_content=inscricao#https:\/\/www.grupomedcof.com.br\/blog\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"320\" src=\"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/02\/Banner-MedCof-Plus-2200x460-11-1024x320.png\" alt=\"Banner de inscri\u00e7\u00e3o para recebimento da newsletter do Grupo MedCof, a Cofletter. Ela traz as principais not\u00edcias da \u00e1rea da sa\u00fade e dos processos seletivos para resid\u00eancia m\u00e9dica.\" class=\"wp-image-33723\" srcset=\"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/02\/Banner-MedCof-Plus-2200x460-11-1024x320.png 1024w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/02\/Banner-MedCof-Plus-2200x460-11-300x94.png 300w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/02\/Banner-MedCof-Plus-2200x460-11-768x240.png 768w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/02\/Banner-MedCof-Plus-2200x460-11-1536x480.png 1536w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/02\/Banner-MedCof-Plus-2200x460-11-2048x640.png 2048w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/02\/Banner-MedCof-Plus-2200x460-11-1343x420.png 1343w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/02\/Banner-MedCof-Plus-2200x460-11-150x47.png 150w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/02\/Banner-MedCof-Plus-2200x460-11-696x218.png 696w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/02\/Banner-MedCof-Plus-2200x460-11-1068x334.png 1068w, https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2025\/02\/Banner-MedCof-Plus-2200x460-11-1920x600.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<h2 id=\"h-irregularidades-da-instituicao\" class=\"wp-block-heading\"><strong>Irregularidades da institui\u00e7\u00e3o<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A promotoria identificou uma <strong>listagem de 1.040 diplomas revalidados em 2025<\/strong>. No entanto, o n\u00famero pode ser ainda maior e precisar\u00e1 de uma apura\u00e7\u00e3o integral ao longo de todo o processo civil. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O MPTO moveu a a\u00e7\u00e3o porque a UnirG teria mantido <strong>o m\u00e9todo de revalida\u00e7\u00e3o simplificada<\/strong> mesmo ap\u00f3s a <strong><a href=\"https:\/\/www.in.gov.br\/web\/dou\/-\/resolucao-cne\/ces-n-2-de-19-de-dezembro-de-2024-603280099\" target=\"_blank\" rel=\"noreferrer noopener\">Resolu\u00e7\u00e3o CNE\/CES n\u00ba 2\/2024<\/a>. <\/strong>A norma federal vedou a pr\u00e1tica e estabeleceu o Revalida como obrigat\u00f3rio para m\u00e9dicos com diplomas estrangeiros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As institui\u00e7\u00f5es tiveram at\u00e9 3 de mar\u00e7o de 2025 para reestruturar seu processo de revalida\u00e7\u00e3o e aderir ao novo programa, o <strong>Exame Nacional de Revalida\u00e7\u00e3o de Diplomas M\u00e9dicos (Revalida)<\/strong>. Entretanto, a Funda\u00e7\u00e3o UnirG teria continuado com o m\u00e9todo simplificado mesmo ap\u00f3s essa data.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m houveram ind\u00edcios de que a UnirG teria emitido mais revalida\u00e7\u00f5es do que poderia. <strong>A <a href=\"https:\/\/abmes.org.br\/arquivos\/legislacoes\/Portaria-mec-1151-2023-06-19.pdf\" type=\"link\" id=\"https:\/\/abmes.org.br\/arquivos\/legislacoes\/Portaria-mec-1151-2023-06-19.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Portaria n\u00ba 1.151\/2023<\/a> do Minist\u00e9rio da Educa\u00e7\u00e3o (MEC) determina que<\/strong> as universidades s\u00f3 podem revalidar diplomas na mesma propor\u00e7\u00e3o de vagas ofertadas no respectivo curso de gradua\u00e7\u00e3o, nesse caso, medicina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por\u00e9m,<strong> a UnirG possui um curso de medicina com apenas 240 vagas anuais autorizadas<\/strong>. Ou seja, as 1.040 revalida\u00e7\u00f5es realizadas ao longo de 2025 ultrapassaram o n\u00famero estabelecido em aproximadamente 800 profissionais.\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A 3\u00aa Promotoria de Justi\u00e7a de Gurupi apontou outras irregularidades: a <strong>contrata\u00e7\u00e3o de uma empresa privada<\/strong> para a triagem e emiss\u00e3o de pareceres sobre os diplomas \u2014 tarefas exclusivas de institui\u00e7\u00f5es p\u00fablicas \u2014, <strong>a falta de edital p\u00fablico com a convoca\u00e7\u00e3o e os crit\u00e9rios de revalida\u00e7\u00e3o<\/strong>, al\u00e9m do recebimento de pedidos por e-mail, e n\u00e3o por sistemas oficiais. Os processos n\u00e3o tramitaram pela <strong>Plataforma Carolina Bori<\/strong>, contrariando exig\u00eancia da Portaria MEC n\u00ba 1.151\/2023.<\/p>\n\n\n\n<h2 id=\"h-a-instituicao-nao-tinha-habilitacao-para-realizar-revalidacoes\" class=\"wp-block-heading\"><strong>A institui\u00e7\u00e3o n\u00e3o tinha habilita\u00e7\u00e3o para realizar revalida\u00e7\u00f5es<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a a\u00e7\u00e3o judicial e o CFM, a UnirG n\u00e3o tinha <strong>compet\u00eancia para a revalida\u00e7\u00e3o de diplomas estrangeiros.<\/strong> Isso porque a autoriza\u00e7\u00e3o exige que o curso de gradua\u00e7\u00e3o tenha<strong> Conceito Preliminar de Curso (CPC) igual ou superior a 3.<\/strong> Contudo, a UnirG tinha <strong>CPC 2 e teve o indicador rebaixado para 1<\/strong>, a pontua\u00e7\u00e3o m\u00ednima na avalia\u00e7\u00e3o do MEC. Desta forma, n\u00e3o teria a compet\u00eancia para realizar revalida\u00e7\u00f5es de diplomas emitidos no exterior.\u00a0<\/p>\n\n\n\n<h2 id=\"h-instituicao-tem-20-dias-para-se-manifestar\" class=\"wp-block-heading\"><strong>Institui\u00e7\u00e3o tem 20 dias para se manifestar<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ainda nesta ter\u00e7a-feira (26), o juiz da 2\u00aa Vara C\u00edvel de Gurupi, Nassib Cleto Mamud,<strong> decidiu ouvir a Funda\u00e7\u00e3o UnirG e a Universidade de Gurupi antes de analisar o pedido do MPTO. <\/strong>A institui\u00e7\u00e3o tem um prazo de 20 dias para se apresentar. O Minist\u00e9rio da Educa\u00e7\u00e3o tamb\u00e9m foi intimado a informar se tem interesse de participar da a\u00e7\u00e3o civil p\u00fablica, em um prazo de at\u00e9 15 dias.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>O m\u00e9todo que te aprova!<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Quer alcan\u00e7ar a aprova\u00e7\u00e3o nas provas de resid\u00eancia m\u00e9dica? Ent\u00e3o seja um&nbsp;<a href=\"https:\/\/www.grupomedcof.com.br\/home\/\" target=\"_blank\" rel=\"noreferrer noopener\">MedCofer<\/a>! Aqui te ajudaremos na busca da aprova\u00e7\u00e3o com conte\u00fados de qualidade e uma&nbsp;<a href=\"https:\/\/www.grupomedcof.com.br\/blog\/presenca-da-medcof-nas-aprovacoes-em-residencia-medica-no-brasil\/\" target=\"_blank\" rel=\"noreferrer noopener\">metodologia que j\u00e1 aprovou mais de 35 mil residentes no pa\u00eds!&nbsp;<\/a>Por fim, acesse o nosso<a href=\"https:\/\/www.youtube.com\/@GrupoMedcof\/featured\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;<strong>canal do youtube&nbsp;<\/strong><\/a>para ver o nosso material.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Conciliar resid\u00eancia em Cl\u00ednica M\u00e9dica e aprova\u00e7\u00e3o em Pneumologia #PapodeAprovado Ep21\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/i27bWq6g0bU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Nesta segunda-feira (25), o Minist\u00e9rio P\u00fablico do Tocantins (MPTO) entrou com uma a\u00e7\u00e3o civil p\u00fablica contra a Funda\u00e7\u00e3o UnirG e a Universidade de Gurupi (UnirG). A a\u00e7\u00e3o visa a suspens\u00e3o imediata e futura anula\u00e7\u00e3o de todos os diplomas estrangeiros de Medicina revalidados pela institui\u00e7\u00e3o desde mar\u00e7o de 2025.\u00a0<\/p>\n","protected":false},"author":41,"featured_media":44910,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[240,173,2920],"tags":[3965,3966,809,138,2382],"ppma_author":[3629],"class_list":["post-44904","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","category-novidades","category-revalida-destaque","tag-diploma-estrangeiro","tag-exame-nacional-de-revalidacao-de-diplomas-medicos","tag-revalida","tag-revalidacao-de-diploma","tag-unirg"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>UnirG pode ter mais de mil diplomas m\u00e9dicos revalidados anulados\u00a0 - Blog de Medcof: conte\u00fados, editais, revalida e mais!<\/title>\n<meta name=\"description\" content=\"A\u00e7\u00e3o civil p\u00fablica aponta que UnirG usou m\u00e9todo proibido e revalidou diplomas de medicina sem autoriza\u00e7\u00e3o do MEC. Justi\u00e7a deu 20 dias para resposta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.grupomedcof.com.br\/blog\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UnirG pode ter mais de mil diplomas m\u00e9dicos revalidados anulados\u00a0\" \/>\n<meta property=\"og:description\" content=\"A\u00e7\u00e3o civil p\u00fablica aponta que UnirG usou m\u00e9todo proibido e revalidou diplomas de medicina sem autoriza\u00e7\u00e3o do MEC. Justi\u00e7a deu 20 dias para resposta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.grupomedcof.com.br\/blog\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Medcof: conte\u00fados, editais, revalida e mais!\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MedCofQbank\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-28T14:16:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-28T14:19:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2026\/05\/Blog-MedCof-56.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nana N\u00f3brega\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nana N\u00f3brega\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\\\/\"},\"author\":{\"name\":\"Nana N\u00f3brega\",\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/70ee71b33df3dbfed84fba8ce195cdc6\"},\"headline\":\"UnirG pode ter mais de mil diplomas m\u00e9dicos revalidados anulados\u00a0\",\"datePublished\":\"2026-05-28T14:16:58+00:00\",\"dateModified\":\"2026-05-28T14:19:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\\\/\"},\"wordCount\":798,\"publisher\":{\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Blog-MedCof-56.jpg\",\"keywords\":[\"diploma estrangeiro\",\"Exame Nacional de Revalida\u00e7\u00e3o de Diplomas M\u00e9dicos\",\"revalida\",\"Revalida\u00e7\u00e3o de Diploma\",\"UnirG\"],\"articleSection\":[\"Not\u00edcias\",\"Novidades\",\"Revalida Destaque\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\\\/\",\"url\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\\\/\",\"name\":\"UnirG pode ter mais de mil diplomas m\u00e9dicos revalidados anulados\u00a0 - Blog de Medcof: conte\u00fados, editais, revalida e mais!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Blog-MedCof-56.jpg\",\"datePublished\":\"2026-05-28T14:16:58+00:00\",\"dateModified\":\"2026-05-28T14:19:11+00:00\",\"description\":\"A\u00e7\u00e3o civil p\u00fablica aponta que UnirG usou m\u00e9todo proibido e revalidou diplomas de medicina sem autoriza\u00e7\u00e3o do MEC. Justi\u00e7a deu 20 dias para resposta.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Blog-MedCof-56.jpg\",\"contentUrl\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Blog-MedCof-56.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"UnirG pode ter mais de mil diplomas m\u00e9dicos revalidados anulados\u00a0\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UnirG pode ter mais de mil diplomas m\u00e9dicos revalidados anulados\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/\",\"name\":\"Blog de Medcof: conte\u00fados, editais, revalida e mais!\",\"description\":\"Acesso o blog de MedCof! Seu portal de conte\u00fados sobre resid\u00eancia m\u00e9dica, an\u00e1lise e editais e muito mais. Clique e confira!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/#organization\"},\"alternateName\":\"Blog de Medcof: conte\u00fados, editais, revalida e mais!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/#organization\",\"name\":\"Grupo MedCof\",\"url\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-medcof.png\",\"contentUrl\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-medcof.png\",\"width\":768,\"height\":269,\"caption\":\"Grupo MedCof\"},\"image\":{\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MedCofQbank\\\/\",\"https:\\\/\\\/www.instagram.com\\\/grupomedcof\\\/\",\"https:\\\/\\\/br.linkedin.com\\\/company\\\/medcof\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCdHMuOHKICxcHwecxN8P-AA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/70ee71b33df3dbfed84fba8ce195cdc6\",\"name\":\"Nana N\u00f3brega\",\"pronouns\":\"ele\\\/ela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-cropped-WhatsApp-Image-2026-03-19-at-09.30.33.jpega4f3600081af811f8cb877d267a26dad\",\"url\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-cropped-WhatsApp-Image-2026-03-19-at-09.30.33.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-cropped-WhatsApp-Image-2026-03-19-at-09.30.33.jpeg\",\"caption\":\"Nana N\u00f3brega\"},\"description\":\"Jornalista pela UNESP. Linguista pela USP. Jornalista da \u00e1rea da sa\u00fade e meio ambiente, fa\u00e7o cobertura de atualiza\u00e7\u00f5es m\u00e9dicas e concursos p\u00fablicos. Especialista em braille e acessibilidade para pessoas cegas ou com baixa vis\u00e3o.\",\"jobTitle\":\"jornalista\",\"url\":\"https:\\\/\\\/www.grupomedcof.com.br\\\/blog\\\/author\\\/nana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"UnirG pode ter mais de mil diplomas m\u00e9dicos revalidados anulados\u00a0 - Blog de Medcof: conte\u00fados, editais, revalida e mais!","description":"A\u00e7\u00e3o civil p\u00fablica aponta que UnirG usou m\u00e9todo proibido e revalidou diplomas de medicina sem autoriza\u00e7\u00e3o do MEC. Justi\u00e7a deu 20 dias para resposta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.grupomedcof.com.br\/blog\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\/","og_locale":"pt_BR","og_type":"article","og_title":"UnirG pode ter mais de mil diplomas m\u00e9dicos revalidados anulados\u00a0","og_description":"A\u00e7\u00e3o civil p\u00fablica aponta que UnirG usou m\u00e9todo proibido e revalidou diplomas de medicina sem autoriza\u00e7\u00e3o do MEC. Justi\u00e7a deu 20 dias para resposta.","og_url":"https:\/\/www.grupomedcof.com.br\/blog\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\/","og_site_name":"Blog de Medcof: conte\u00fados, editais, revalida e mais!","article_publisher":"https:\/\/www.facebook.com\/MedCofQbank\/","article_published_time":"2026-05-28T14:16:58+00:00","article_modified_time":"2026-05-28T14:19:11+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2026\/05\/Blog-MedCof-56.jpg","type":"image\/jpeg"}],"author":"Nana N\u00f3brega","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Nana N\u00f3brega","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.grupomedcof.com.br\/blog\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\/#article","isPartOf":{"@id":"https:\/\/www.grupomedcof.com.br\/blog\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\/"},"author":{"name":"Nana N\u00f3brega","@id":"https:\/\/www.grupomedcof.com.br\/blog\/#\/schema\/person\/70ee71b33df3dbfed84fba8ce195cdc6"},"headline":"UnirG pode ter mais de mil diplomas m\u00e9dicos revalidados anulados\u00a0","datePublished":"2026-05-28T14:16:58+00:00","dateModified":"2026-05-28T14:19:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.grupomedcof.com.br\/blog\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\/"},"wordCount":798,"publisher":{"@id":"https:\/\/www.grupomedcof.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.grupomedcof.com.br\/blog\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\/#primaryimage"},"thumbnailUrl":"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2026\/05\/Blog-MedCof-56.jpg","keywords":["diploma estrangeiro","Exame Nacional de Revalida\u00e7\u00e3o de Diplomas M\u00e9dicos","revalida","Revalida\u00e7\u00e3o de Diploma","UnirG"],"articleSection":["Not\u00edcias","Novidades","Revalida Destaque"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.grupomedcof.com.br\/blog\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\/","url":"https:\/\/www.grupomedcof.com.br\/blog\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\/","name":"UnirG pode ter mais de mil diplomas m\u00e9dicos revalidados anulados\u00a0 - Blog de Medcof: conte\u00fados, editais, revalida e mais!","isPartOf":{"@id":"https:\/\/www.grupomedcof.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.grupomedcof.com.br\/blog\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\/#primaryimage"},"image":{"@id":"https:\/\/www.grupomedcof.com.br\/blog\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\/#primaryimage"},"thumbnailUrl":"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2026\/05\/Blog-MedCof-56.jpg","datePublished":"2026-05-28T14:16:58+00:00","dateModified":"2026-05-28T14:19:11+00:00","description":"A\u00e7\u00e3o civil p\u00fablica aponta que UnirG usou m\u00e9todo proibido e revalidou diplomas de medicina sem autoriza\u00e7\u00e3o do MEC. Justi\u00e7a deu 20 dias para resposta.","breadcrumb":{"@id":"https:\/\/www.grupomedcof.com.br\/blog\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.grupomedcof.com.br\/blog\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.grupomedcof.com.br\/blog\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\/#primaryimage","url":"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2026\/05\/Blog-MedCof-56.jpg","contentUrl":"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2026\/05\/Blog-MedCof-56.jpg","width":1920,"height":1080,"caption":"UnirG pode ter mais de mil diplomas m\u00e9dicos revalidados anulados\u00a0"},{"@type":"BreadcrumbList","@id":"https:\/\/www.grupomedcof.com.br\/blog\/unirg-pode-ter-mais-de-mil-diplomas-medicos-revalidados-anulados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.grupomedcof.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"UnirG pode ter mais de mil diplomas m\u00e9dicos revalidados anulados\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.grupomedcof.com.br\/blog\/#website","url":"https:\/\/www.grupomedcof.com.br\/blog\/","name":"Blog de Medcof: conte\u00fados, editais, revalida e mais!","description":"Acesso o blog de MedCof! Seu portal de conte\u00fados sobre resid\u00eancia m\u00e9dica, an\u00e1lise e editais e muito mais. Clique e confira!","publisher":{"@id":"https:\/\/www.grupomedcof.com.br\/blog\/#organization"},"alternateName":"Blog de Medcof: conte\u00fados, editais, revalida e mais!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.grupomedcof.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.grupomedcof.com.br\/blog\/#organization","name":"Grupo MedCof","url":"https:\/\/www.grupomedcof.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.grupomedcof.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2022\/01\/logo-medcof.png","contentUrl":"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2022\/01\/logo-medcof.png","width":768,"height":269,"caption":"Grupo MedCof"},"image":{"@id":"https:\/\/www.grupomedcof.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MedCofQbank\/","https:\/\/www.instagram.com\/grupomedcof\/","https:\/\/br.linkedin.com\/company\/medcof","https:\/\/www.youtube.com\/channel\/UCdHMuOHKICxcHwecxN8P-AA"]},{"@type":"Person","@id":"https:\/\/www.grupomedcof.com.br\/blog\/#\/schema\/person\/70ee71b33df3dbfed84fba8ce195cdc6","name":"Nana N\u00f3brega","pronouns":"ele\/ela","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2026\/03\/cropped-cropped-WhatsApp-Image-2026-03-19-at-09.30.33.jpega4f3600081af811f8cb877d267a26dad","url":"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2026\/03\/cropped-cropped-WhatsApp-Image-2026-03-19-at-09.30.33.jpeg","contentUrl":"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2026\/03\/cropped-cropped-WhatsApp-Image-2026-03-19-at-09.30.33.jpeg","caption":"Nana N\u00f3brega"},"description":"Jornalista pela UNESP. Linguista pela USP. Jornalista da \u00e1rea da sa\u00fade e meio ambiente, fa\u00e7o cobertura de atualiza\u00e7\u00f5es m\u00e9dicas e concursos p\u00fablicos. Especialista em braille e acessibilidade para pessoas cegas ou com baixa vis\u00e3o.","jobTitle":"jornalista","url":"https:\/\/www.grupomedcof.com.br\/blog\/author\/nana\/"}]}},"authors":[{"term_id":3629,"user_id":41,"is_guest":0,"slug":"nana","display_name":"Nana N\u00f3brega","avatar_url":{"url":"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2026\/03\/cropped-cropped-WhatsApp-Image-2026-03-19-at-09.30.33.jpeg","url2x":"https:\/\/www.grupomedcof.com.br\/blog\/wp-content\/uploads\/2026\/03\/cropped-cropped-WhatsApp-Image-2026-03-19-at-09.30.33.jpeg"},"0":null,"1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/www.grupomedcof.com.br\/blog\/wp-json\/wp\/v2\/posts\/44904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.grupomedcof.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.grupomedcof.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.grupomedcof.com.br\/blog\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/www.grupomedcof.com.br\/blog\/wp-json\/wp\/v2\/comments?post=44904"}],"version-history":[{"count":4,"href":"https:\/\/www.grupomedcof.com.br\/blog\/wp-json\/wp\/v2\/posts\/44904\/revisions"}],"predecessor-version":[{"id":44914,"href":"https:\/\/www.grupomedcof.com.br\/blog\/wp-json\/wp\/v2\/posts\/44904\/revisions\/44914"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grupomedcof.com.br\/blog\/wp-json\/wp\/v2\/media\/44910"}],"wp:attachment":[{"href":"https:\/\/www.grupomedcof.com.br\/blog\/wp-json\/wp\/v2\/media?parent=44904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.grupomedcof.com.br\/blog\/wp-json\/wp\/v2\/categories?post=44904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.grupomedcof.com.br\/blog\/wp-json\/wp\/v2\/tags?post=44904"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.grupomedcof.com.br\/blog\/wp-json\/wp\/v2\/ppma_author?post=44904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}